{"id":1730,"date":"2020-09-11T10:12:46","date_gmt":"2020-09-11T08:12:46","guid":{"rendered":"https:\/\/mirkokulig.com\/?p=1730"},"modified":"2020-09-21T09:23:36","modified_gmt":"2020-09-21T07:23:36","slug":"il-porto-invisibile-di-orbetello","status":"publish","type":"post","link":"https:\/\/mirkokulig.com\/en\/il-porto-invisibile-di-orbetello\/","title":{"rendered":"Il porto invisibile di Orbetello"},"content":{"rendered":"<p>di Mario Pincherle<\/p>\n\n\n\n<p>In questo introvabile libro, pubblicato negli anni &#8217;80, Mario Pincherle espone la sua ricerca sulle mura poligonali di Orbetello, arrivando ad ipotizzare che i tomboli di Giannella e Feniglia che oggi racchiudono la laguna di Orbetello, siano stati formati con l&#8217;intervento dell&#8217;uomo.<\/p>\n\n\n\n<p>Avendo cercato questo libro per oltre un anno, quando finalmente l&#8217;ho trovato l&#8217;ho scansionato e lo metto a disposizione per il download.<\/p>\n\n\n\n<p><a href=\"https:\/\/mirkokulig.com\/wp-content\/uploads\/2020\/09\/Il-Porto-Invisibile-di-Orbetello-Mario-Pincherle-super-light.pdf\">Scarica la versione in qualit\u00e0 standard<\/a> (55 MB)<\/p>\n\n\n\n<p><a href=\"https:\/\/mirkokulig.com\/wp-content\/uploads\/2020\/09\/Il-Porto-Invisibile-di-Orbetello-Mario-Pincherle.zip\">Scarica la versione in alta qualit\u00e0<\/a> (185 MB)<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p id=\"block-bdcb73b5-41a3-4c76-aad9-d5a13409d26e\">Il mantenimento del sito ha un costo. Se hai apprezzato i contenuti ti invito gentilmente a farmi una donazione con importo a tua scelta. Grazie!<\/p>\n\n\n\n<p id=\"block-7ccaed14-13aa-46c9-a840-a1ead036a0ae\">Site maintenance has a cost. If you liked what you found on this website, I kindly invite you to donate any amount of your choice. Thank you!<\/p>\n\n\n<style>\r\n        .wpedon-container .wpedon-select,\r\n        .wpedon-container .wpedon-input {\r\n            width: 107px;\r\n            min-width: 107px;\r\n            max-width: 107px;\r\n        }\r\n    <\/style><div class='wpedon-container wpedon-align-left'><form target='_blank' action='https:\/\/www.paypal.com\/cgi-bin\/webscr' method='post' class='wpedon-form'><input type='hidden' name='cmd' value='_donations' \/><input type='hidden' name='business' value='GYVNMRKTJF9QN' \/><input type='hidden' name='currency_code' value='EUR' \/><input type='hidden' name='notify_url' value='https:\/\/mirkokulig.com\/wp-admin\/admin-post.php?action=add_wpedon_button_ipn'><input type='hidden' name='lc' value='en_US'><input type='hidden' name='bn' value='WPPlugin_SP'><input type='hidden' name='return' value='' \/><input type='hidden' name='cancel_return' value='' \/><input class='wpedon_paypalbuttonimage' type='image' src='https:\/\/www.paypalobjects.com\/webstatic\/en_US\/btn\/btn_donate_92x26.png' border='0' name='submit' alt='Make your payments with PayPal. It is free, secure, effective.' style='border: none;'><img alt='' border='0' style='border:none;display:none;' src='https:\/\/www.paypal.com\/en_US\/i\/scr\/pixel.gif' width='1' height='1'><input type='hidden' name='amount' id='amount_fd4d03312e5e39c2e916178182dc5bcd' value='' \/><input type='hidden' name='price' id='price_fd4d03312e5e39c2e916178182dc5bcd' value='' \/><input type='hidden' name='item_number' value='' \/><input type='hidden' name='item_name' value='Donation' \/><input type='hidden' name='name' value='Donation' \/><input type='hidden' name='custom' value='1700'><input type='hidden' name='no_shipping' value='1'><input type='hidden' name='no_note' value='1'><input type='hidden' name='currency_code' value='EUR'><\/form><\/div>","protected":false},"excerpt":{"rendered":"<p>di Mario Pincherle In questo introvabile libro, pubblicato negli anni &#8217;80, Mario Pincherle espone la sua ricerca sulle mura poligonali&hellip;<\/p>","protected":false},"author":1,"featured_media":1732,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[407,168,408,405,406],"class_list":["post-1730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archeologia","tag-mario-pincherle","tag-mura-poligonali","tag-mura-poligonali-toscana","tag-orbetello","tag-porto-invisibile"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts\/1730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/comments?post=1730"}],"version-history":[{"count":3,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts\/1730\/revisions"}],"predecessor-version":[{"id":1745,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts\/1730\/revisions\/1745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/media\/1732"}],"wp:attachment":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/media?parent=1730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/categories?post=1730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/tags?post=1730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}