{"id":821,"date":"2019-08-02T17:33:28","date_gmt":"2019-08-02T15:33:28","guid":{"rendered":"https:\/\/mirkokulig.com\/?p=821"},"modified":"2019-09-20T16:31:01","modified_gmt":"2019-09-20T14:31:01","slug":"video-laos-lan-chang-il-paese-di-un-milione-di-elefanti","status":"publish","type":"post","link":"https:\/\/mirkokulig.com\/en\/video-laos-lan-chang-il-paese-di-un-milione-di-elefanti\/","title":{"rendered":"Documentario &#8211; Laos &#8211; Lan Chang &#8211; Il Paese di un milione di elefanti"},"content":{"rendered":"<p> Il poco conosciuto Laos vive ancora oggi una realt\u00e0 molto tranquilla che ha permesso la preservazione della sua forte tradizione orientale. Un paese che si sta&#8217; lentamente conformando ad un mondo in rapido cambiamento. Le interminabili catene montuose e le vaste valli del Mekong danno un carattere al paese che in passato ha permesso la nascita e lo sviluppo di potenti regni. <\/p>\n\n\n\n<p>Filmato nel 2007 <\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_35605\"  width=\"688\" height=\"516\"  data-origwidth=\"688\" data-origheight=\"516\" src=\"https:\/\/www.youtube.com\/embed\/VFZ2cW7SPQE?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Il poco conosciuto Laos vive ancora oggi una realt\u00e0 molto tranquilla che ha permesso la preservazione della sua forte tradizione&hellip;<\/p>","protected":false},"author":1,"featured_media":822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[203,200,199,202],"class_list":["post-821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video","tag-documentario-laos","tag-lan-chang","tag-laos","tag-vientiane"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":2,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts\/821\/revisions"}],"predecessor-version":[{"id":831,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts\/821\/revisions\/831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/media\/822"}],"wp:attachment":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/media?parent=821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/categories?post=821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/tags?post=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}