{"id":447,"count":1,"description":"","link":"https:\/\/mirkokulig.com\/en\/tag\/puglia-archeologia\/","name":"puglia archeologia","slug":"puglia-archeologia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/tags\/447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mirkokulig.com\/en\/wp-json\/wp\/v2\/posts?tags=447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}